{"id":88652,"date":"2026-05-02T04:06:25","date_gmt":"2026-05-02T04:06:25","guid":{"rendered":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar\/"},"modified":"2026-05-12T07:52:12","modified_gmt":"2026-05-12T07:52:12","slug":"set-de-4-tizas-para-personalizar-con-logo","status":"publish","type":"product","link":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/","title":{"rendered":"Set de 4 tizas  para personalizar con logo"},"content":{"rendered":"<p>4 tizas de colores en una caja de cart\u00f3n. No permite la grabaci\u00f3n de los componentes. \u00a1Advertencia! No apto para ni\u00f1os menores de tres a\u00f1os. Piezas peque\u00f1as. Peligro de asfixia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Descuentos por cantidades<\/strong><br \/>&#8211; a partir de 250 unidades: 0,58 \u20ac\/ud<br \/>&#8211; a partir de 500 unidades: 0,56 \u20ac\/ud<br \/>&#8211; a partir de 1000 unidades: 0,56 \u20ac\/ud<\/p>\n<p>Para cantidades superiores a las aqu\u00ed indicadas, no dudes en ponerte en contacto con nuestro departamento comercial o <a href='https:\/\/adl-regalosempresa.com\/tiendaonline\/solicitud-presupuesto\/'>pedirnos presupuesto personalizado<\/a>, ajustaremos el presupuesto a tus necesidades.<\/p>\n","protected":false},"featured_media":88654,"template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[4287,4299],"product_tag":[],"class_list":{"0":"post-88652","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-boligrafos-y-escritura","7":"product_cat-sets-de-colorear-sets-de-color","8":"pa_alto-107-cm","9":"pa_ancho-97-cm","10":"pa_color-natural","11":"pa_color-simple-natural","12":"pa_marca-unbranded","13":"pa_material-papel","14":"pa_peso-150-gr","16":"first","17":"instock","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-variable","22":"entry","23":"content-bg","24":"loop-entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Merchandising Set de 4 tizas para personalizar con logo - ADL<\/title>\n<meta name=\"description\" content=\"Art\u00edculo de merchandising Set de 4 tizas &quot;Screech&quot;. 4 tizas de colores en una caja de cart\u00f3n. No permite la grabaci\u00f3n de los componentes. \u00a1Advertencia! No apto para ni\u00f1os menores de tres a\u00f1os. Piezas peque\u00f1as. Peligro de asfixia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Merchandising Set de 4 tizas para personalizar con logo - ADL\" \/>\n<meta property=\"og:description\" content=\"Art\u00edculo de merchandising Set de 4 tizas &quot;Screech&quot;. 4 tizas de colores en una caja de cart\u00f3n. No permite la grabaci\u00f3n de los componentes. \u00a1Advertencia! No apto para ni\u00f1os menores de tres a\u00f1os. Piezas peque\u00f1as. Peligro de asfixia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/\" \/>\n<meta property=\"og:site_name\" content=\"ADL Comunicaci\u00f3n\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T07:52:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2022\/06\/10705800.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Merchandising Set de 4 tizas para personalizar con logo - ADL\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/\",\"name\":\"Merchandising Set de 4 tizas para personalizar con logo - ADL\",\"isPartOf\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2022\/06\/10705800.jpg\",\"datePublished\":\"2026-05-02T04:06:25+00:00\",\"dateModified\":\"2026-05-12T07:52:12+00:00\",\"description\":\"Art\u00edculo de merchandising Set de 4 tizas \\\"Screech\\\". 4 tizas de colores en una caja de cart\u00f3n. No permite la grabaci\u00f3n de los componentes. \u00a1Advertencia! No apto para ni\u00f1os menores de tres a\u00f1os. Piezas peque\u00f1as. Peligro de asfixia.\",\"breadcrumb\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/#primaryimage\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2022\/06\/10705800.jpg\",\"contentUrl\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2022\/06\/10705800.jpg\",\"width\":1600,\"height\":1600,\"caption\":\"Set de 4 tizas \\\"Screech\\\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Set de 4 tizas para personalizar con logo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/\",\"name\":\"ADL Comunicaci\u00f3n\",\"description\":\"Regalos de empresa\",\"publisher\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization\",\"name\":\"ADL Comunicaci\u00f3n\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png\",\"contentUrl\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png\",\"width\":407,\"height\":185,\"caption\":\"ADL Comunicaci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Merchandising Set de 4 tizas para personalizar con logo - ADL","description":"Art\u00edculo de merchandising Set de 4 tizas \"Screech\". 4 tizas de colores en una caja de cart\u00f3n. No permite la grabaci\u00f3n de los componentes. \u00a1Advertencia! No apto para ni\u00f1os menores de tres a\u00f1os. Piezas peque\u00f1as. Peligro de asfixia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/","og_locale":"es_ES","og_type":"article","og_title":"Merchandising Set de 4 tizas para personalizar con logo - ADL","og_description":"Art\u00edculo de merchandising Set de 4 tizas \"Screech\". 4 tizas de colores en una caja de cart\u00f3n. No permite la grabaci\u00f3n de los componentes. \u00a1Advertencia! No apto para ni\u00f1os menores de tres a\u00f1os. Piezas peque\u00f1as. Peligro de asfixia.","og_url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/","og_site_name":"ADL Comunicaci\u00f3n","article_modified_time":"2026-05-12T07:52:12+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2022\/06\/10705800.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Merchandising Set de 4 tizas para personalizar con logo - ADL","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/","name":"Merchandising Set de 4 tizas para personalizar con logo - ADL","isPartOf":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/#primaryimage"},"image":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/#primaryimage"},"thumbnailUrl":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2022\/06\/10705800.jpg","datePublished":"2026-05-02T04:06:25+00:00","dateModified":"2026-05-12T07:52:12+00:00","description":"Art\u00edculo de merchandising Set de 4 tizas \"Screech\". 4 tizas de colores en una caja de cart\u00f3n. No permite la grabaci\u00f3n de los componentes. \u00a1Advertencia! No apto para ni\u00f1os menores de tres a\u00f1os. Piezas peque\u00f1as. Peligro de asfixia.","breadcrumb":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/#primaryimage","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2022\/06\/10705800.jpg","contentUrl":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2022\/06\/10705800.jpg","width":1600,"height":1600,"caption":"Set de 4 tizas \"Screech\""},{"@type":"BreadcrumbList","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-4-tizas-para-personalizar-con-logo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/adl-regalosempresa.com\/tiendaonline\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/adl-regalosempresa.com\/tiendaonline\/tienda\/"},{"@type":"ListItem","position":3,"name":"Set de 4 tizas para personalizar con logo"}]},{"@type":"WebSite","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/","name":"ADL Comunicaci\u00f3n","description":"Regalos de empresa","publisher":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adl-regalosempresa.com\/tiendaonline\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization","name":"ADL Comunicaci\u00f3n","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png","contentUrl":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png","width":407,"height":185,"caption":"ADL Comunicaci\u00f3n"},"image":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product\/88652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/media\/88654"}],"wp:attachment":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/media?parent=88652"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product_brand?post=88652"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product_cat?post=88652"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product_tag?post=88652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}