{"id":143407,"date":"2026-06-14T04:54:29","date_gmt":"2026-06-14T04:54:29","guid":{"rendered":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-para-personalizar-con-logo\/"},"modified":"2026-07-15T08:34:18","modified_gmt":"2026-07-15T08:34:18","slug":"set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo","status":"publish","type":"product","link":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/","title":{"rendered":"Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle para personalizar con logo"},"content":{"rendered":"<p>El set de regalo Ocean Bottle de 500\u00a0ml cuenta con un sistema de tapa modular \u00fanico en su clase que permite una transici\u00f3n perfecta de una actividad a otra gracias a sus 3 tapas intercambiables. Este set de regalo consta de una botella Ocean Bottle de 500\u00a0ml con 3 tapas: la tapa original (para beber todos los d\u00edas sin fugas), la tapa GO (con una pajita que se puede cerrar) y la tapa Brew (para disfrutar de bebidas calientes sobre la marcha). Dise\u00f1ada con doble funci\u00f3n de apertura, esta botella modular facilita el acceso para llenarla, limpiarla y a\u00f1adir hielo. El set de regalo est\u00e1 fabricado con materiales reciclados y es apto para el lavavajillas. Se presenta en una caja de regalo de cart\u00f3n reciclado de origen responsable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Descuentos por cantidades<\/strong><br \/>&#8211; a partir de 50 unidades: 69,36 \u20ac\/ud<br \/>&#8211; a partir de 100 unidades: 67,98 \u20ac\/ud<br \/>&#8211; a partir de 250 unidades: 67,32 \u20ac\/ud<\/p>\n<p>Para cantidades superiores a las aqu\u00ed indicadas, no dudes en ponerte en contacto con nuestro departamento comercial o <a href='https:\/\/adl-regalosempresa.com\/tiendaonline\/solicitud-presupuesto\/'>pedirnos presupuesto personalizado<\/a>, ajustaremos el presupuesto a tus necesidades.<\/p>\n","protected":false},"featured_media":143409,"template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[3372,3373],"product_tag":[],"class_list":{"0":"post-143407","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-articulos-para-bebidas","7":"product_cat-botellas-de-agua","8":"pa_alto-233-cm","9":"pa_color-arenisca","10":"pa_color-azul-oceano","11":"pa_color-negro-obsidiana","12":"pa_color-simple-azul","13":"pa_color-simple-natural","14":"pa_color-simple-negro-intenso","15":"pa_diametro-68-cm","16":"pa_marca-ocean-bottle","17":"pa_material-acero-inoxidable-reciclado","18":"pa_peso-271-gr","20":"first","21":"instock","22":"taxable","23":"shipping-taxable","24":"purchasable","25":"product-type-variable","26":"entry","27":"content-bg","28":"loop-entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Merchandising Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle para personalizar con logo - ADL<\/title>\n<meta name=\"description\" content=\"Art\u00edculo de merchandising Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle. El set de regalo Ocean Bottle de 500\u00a0ml cuenta con un sistema de tapa modular \u00fanico en su clase que permite una transici\u00f3n perfecta de una actividad a otra gracias a sus 3 tapas intercambiables. Este set de regalo consta de una botella Ocean Bottle de 500\u00a0ml con 3 tapas: la tapa original (para beber todos los d\u00edas sin fugas), la tapa GO (con una pajita que se puede cerrar) y la tapa Brew (para disfrutar de bebidas calientes sobre la marcha). Dise\u00f1ada con doble funci\u00f3n de apertura, esta botella modular facilita el acceso para llenarla, limpiarla y a\u00f1adir hielo. El set de regalo est\u00e1 fabricado con materiales reciclados y es apto para el lavavajillas. Se presenta en una caja de regalo de cart\u00f3n reciclado de origen responsable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Merchandising Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle para personalizar con logo - ADL\" \/>\n<meta property=\"og:description\" content=\"Art\u00edculo de merchandising Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle. El set de regalo Ocean Bottle de 500\u00a0ml cuenta con un sistema de tapa modular \u00fanico en su clase que permite una transici\u00f3n perfecta de una actividad a otra gracias a sus 3 tapas intercambiables. Este set de regalo consta de una botella Ocean Bottle de 500\u00a0ml con 3 tapas: la tapa original (para beber todos los d\u00edas sin fugas), la tapa GO (con una pajita que se puede cerrar) y la tapa Brew (para disfrutar de bebidas calientes sobre la marcha). Dise\u00f1ada con doble funci\u00f3n de apertura, esta botella modular facilita el acceso para llenarla, limpiarla y a\u00f1adir hielo. El set de regalo est\u00e1 fabricado con materiales reciclados y es apto para el lavavajillas. Se presenta en una caja de regalo de cart\u00f3n reciclado de origen responsable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/\" \/>\n<meta property=\"og:site_name\" content=\"ADL Comunicaci\u00f3n\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T08:34:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2025\/08\/11318506.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Merchandising Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle para personalizar con logo - ADL\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/\",\"name\":\"Merchandising Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle para personalizar con logo - ADL\",\"isPartOf\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2025\/08\/11318506.jpg\",\"datePublished\":\"2026-06-14T04:54:29+00:00\",\"dateModified\":\"2026-07-15T08:34:18+00:00\",\"description\":\"Art\u00edculo de merchandising Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle. El set de regalo Ocean Bottle de 500\u00a0ml cuenta con un sistema de tapa modular \u00fanico en su clase que permite una transici\u00f3n perfecta de una actividad a otra gracias a sus 3 tapas intercambiables. Este set de regalo consta de una botella Ocean Bottle de 500\u00a0ml con 3 tapas: la tapa original (para beber todos los d\u00edas sin fugas), la tapa GO (con una pajita que se puede cerrar) y la tapa Brew (para disfrutar de bebidas calientes sobre la marcha). Dise\u00f1ada con doble funci\u00f3n de apertura, esta botella modular facilita el acceso para llenarla, limpiarla y a\u00f1adir hielo. El set de regalo est\u00e1 fabricado con materiales reciclados y es apto para el lavavajillas. Se presenta en una caja de regalo de cart\u00f3n reciclado de origen responsable.\",\"breadcrumb\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/#primaryimage\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2025\/08\/11318506.jpg\",\"contentUrl\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2025\/08\/11318506.jpg\",\"width\":1600,\"height\":1600,\"caption\":\"Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle para personalizar con logo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/\",\"name\":\"ADL Comunicaci\u00f3n\",\"description\":\"Regalos de empresa\",\"publisher\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization\",\"name\":\"ADL Comunicaci\u00f3n\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png\",\"contentUrl\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png\",\"width\":407,\"height\":185,\"caption\":\"ADL Comunicaci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Merchandising Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle para personalizar con logo - ADL","description":"Art\u00edculo de merchandising Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle. El set de regalo Ocean Bottle de 500\u00a0ml cuenta con un sistema de tapa modular \u00fanico en su clase que permite una transici\u00f3n perfecta de una actividad a otra gracias a sus 3 tapas intercambiables. Este set de regalo consta de una botella Ocean Bottle de 500\u00a0ml con 3 tapas: la tapa original (para beber todos los d\u00edas sin fugas), la tapa GO (con una pajita que se puede cerrar) y la tapa Brew (para disfrutar de bebidas calientes sobre la marcha). Dise\u00f1ada con doble funci\u00f3n de apertura, esta botella modular facilita el acceso para llenarla, limpiarla y a\u00f1adir hielo. El set de regalo est\u00e1 fabricado con materiales reciclados y es apto para el lavavajillas. Se presenta en una caja de regalo de cart\u00f3n reciclado de origen responsable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/","og_locale":"es_ES","og_type":"article","og_title":"Merchandising Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle para personalizar con logo - ADL","og_description":"Art\u00edculo de merchandising Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle. El set de regalo Ocean Bottle de 500\u00a0ml cuenta con un sistema de tapa modular \u00fanico en su clase que permite una transici\u00f3n perfecta de una actividad a otra gracias a sus 3 tapas intercambiables. Este set de regalo consta de una botella Ocean Bottle de 500\u00a0ml con 3 tapas: la tapa original (para beber todos los d\u00edas sin fugas), la tapa GO (con una pajita que se puede cerrar) y la tapa Brew (para disfrutar de bebidas calientes sobre la marcha). Dise\u00f1ada con doble funci\u00f3n de apertura, esta botella modular facilita el acceso para llenarla, limpiarla y a\u00f1adir hielo. El set de regalo est\u00e1 fabricado con materiales reciclados y es apto para el lavavajillas. Se presenta en una caja de regalo de cart\u00f3n reciclado de origen responsable.","og_url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/","og_site_name":"ADL Comunicaci\u00f3n","article_modified_time":"2026-07-15T08:34:18+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2025\/08\/11318506.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Merchandising Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle para personalizar con logo - ADL","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/","name":"Merchandising Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle para personalizar con logo - ADL","isPartOf":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/#primaryimage"},"image":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/#primaryimage"},"thumbnailUrl":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2025\/08\/11318506.jpg","datePublished":"2026-06-14T04:54:29+00:00","dateModified":"2026-07-15T08:34:18+00:00","description":"Art\u00edculo de merchandising Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle. El set de regalo Ocean Bottle de 500\u00a0ml cuenta con un sistema de tapa modular \u00fanico en su clase que permite una transici\u00f3n perfecta de una actividad a otra gracias a sus 3 tapas intercambiables. Este set de regalo consta de una botella Ocean Bottle de 500\u00a0ml con 3 tapas: la tapa original (para beber todos los d\u00edas sin fugas), la tapa GO (con una pajita que se puede cerrar) y la tapa Brew (para disfrutar de bebidas calientes sobre la marcha). Dise\u00f1ada con doble funci\u00f3n de apertura, esta botella modular facilita el acceso para llenarla, limpiarla y a\u00f1adir hielo. El set de regalo est\u00e1 fabricado con materiales reciclados y es apto para el lavavajillas. Se presenta en una caja de regalo de cart\u00f3n reciclado de origen responsable.","breadcrumb":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/#primaryimage","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2025\/08\/11318506.jpg","contentUrl":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2025\/08\/11318506.jpg","width":1600,"height":1600,"caption":"Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle"},{"@type":"BreadcrumbList","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/set-de-regalo-3-en-1-de-500-ml-ocean-bottle-para-personalizar-con-logo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/adl-regalosempresa.com\/tiendaonline\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/adl-regalosempresa.com\/tiendaonline\/tienda\/"},{"@type":"ListItem","position":3,"name":"Set de regalo 3 en 1 de 500\u00a0ml Ocean Bottle para personalizar con logo"}]},{"@type":"WebSite","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/","name":"ADL Comunicaci\u00f3n","description":"Regalos de empresa","publisher":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adl-regalosempresa.com\/tiendaonline\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization","name":"ADL Comunicaci\u00f3n","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png","contentUrl":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png","width":407,"height":185,"caption":"ADL Comunicaci\u00f3n"},"image":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product\/143407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/media\/143409"}],"wp:attachment":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/media?parent=143407"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product_brand?post=143407"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product_cat?post=143407"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product_tag?post=143407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}