{"id":135626,"date":"2026-09-02T04:45:32","date_gmt":"2026-09-02T04:45:32","guid":{"rendered":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-para-personalizar-con-logo\/"},"modified":"2026-09-02T08:24:16","modified_gmt":"2026-09-02T08:24:16","slug":"taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo","status":"publish","type":"product","link":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\/","title":{"rendered":"Taza de espresso apilable de 130 ml con fondo de arcilla Olympia para personalizar con logo"},"content":{"rendered":"<p>La taza de caf\u00e9 expreso Olympia tiene un dise\u00f1o apilable que ocupa poco espacio y una capacidad de 130\u00a0ml. Acabado mate. Se presenta en una caja de cart\u00f3n reciclado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Descuentos por cantidades<\/strong><br \/>&#8211; a partir de 100 unidades: 2,6 \u20ac\/ud<br \/>&#8211; a partir de 250 unidades: 2,6 \u20ac\/ud<br \/>&#8211; a partir de 1000 unidades: 2,55 \u20ac\/ud<\/p>\n<p>Para cantidades superiores a las aqu\u00ed indicadas, no dudes en ponerte en contacto con nuestro departamento comercial o <a href='https:\/\/adl-regalosempresa.com\/tiendaonline\/solicitud-presupuesto\/'>pedirnos presupuesto personalizado<\/a>, ajustaremos el presupuesto a tus necesidades.<\/p>\n","protected":false},"featured_media":135628,"template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[3372,3846],"product_tag":[],"class_list":["post-135626","product","type-product","status-publish","has-post-thumbnail","product_cat-articulos-para-bebidas","product_cat-tazas-estandar","pa_alto-71-cm","pa_ancho-5-cm","pa_color-azul-marino","pa_color-blanco","pa_color-gris","pa_color-naranja","pa_color-simple-azul","pa_color-simple-blanco","pa_color-simple-gris","pa_color-simple-naranja","pa_diametro-5-cm","pa_marca-unbranded","pa_material-ceramica","pa_peso-230-gr","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","entry","content-bg","loop-entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Merchandising Taza de espresso apilable de 130 ml con fondo de arcilla Olympia para personalizar con logo - ADL<\/title>\n<meta name=\"description\" content=\"Art\u00edculo de merchandising Taza de espresso apilable de 130 ml con fondo de arcilla Olympia. La taza de caf\u00e9 expreso Olympia tiene un dise\u00f1o apilable que ocupa poco espacio y una capacidad de 130\u00a0ml. Acabado mate. Se presenta en una caja de cart\u00f3n reciclado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Merchandising Taza de espresso apilable de 130 ml con fondo de arcilla Olympia para personalizar con logo - ADL\" \/>\n<meta property=\"og:description\" content=\"Art\u00edculo de merchandising Taza de espresso apilable de 130 ml con fondo de arcilla Olympia. La taza de caf\u00e9 expreso Olympia tiene un dise\u00f1o apilable que ocupa poco espacio y una capacidad de 130\u00a0ml. Acabado mate. Se presenta en una caja de cart\u00f3n reciclado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\/\" \/>\n<meta property=\"og:site_name\" content=\"ADL Comunicaci\u00f3n\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T08:24:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2024\/08\/10080501.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Merchandising Taza de espresso apilable de 130 ml con fondo de arcilla Olympia para personalizar con logo - ADL\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/articulos\\\/merchandising\\\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\\\/\",\"url\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/articulos\\\/merchandising\\\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\\\/\",\"name\":\"Merchandising Taza de espresso apilable de 130 ml con fondo de arcilla Olympia para personalizar con logo - ADL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/articulos\\\/merchandising\\\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/articulos\\\/merchandising\\\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/10080501.jpg\",\"datePublished\":\"2026-09-02T04:45:32+00:00\",\"dateModified\":\"2026-09-02T08:24:16+00:00\",\"description\":\"Art\u00edculo de merchandising Taza de espresso apilable de 130 ml con fondo de arcilla Olympia. La taza de caf\u00e9 expreso Olympia tiene un dise\u00f1o apilable que ocupa poco espacio y una capacidad de 130\u00a0ml. Acabado mate. Se presenta en una caja de cart\u00f3n reciclado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/articulos\\\/merchandising\\\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/articulos\\\/merchandising\\\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/articulos\\\/merchandising\\\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/10080501.jpg\",\"contentUrl\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/10080501.jpg\",\"width\":1600,\"height\":1600,\"caption\":\"Taza de espresso apilable de 130 ml con fondo de arcilla Olympia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/articulos\\\/merchandising\\\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Taza de espresso apilable de 130 ml con fondo de arcilla Olympia para personalizar con logo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/#website\",\"url\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/\",\"name\":\"ADL Comunicaci\u00f3n\",\"description\":\"Regalos de empresa\",\"publisher\":{\"@id\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/#organization\",\"name\":\"ADL Comunicaci\u00f3n\",\"url\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/logo-adl-wp.png\",\"contentUrl\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/logo-adl-wp.png\",\"width\":407,\"height\":185,\"caption\":\"ADL Comunicaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/adl-regalosempresa.com\\\/tiendaonline\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Merchandising Taza de espresso apilable de 130 ml con fondo de arcilla Olympia para personalizar con logo - ADL","description":"Art\u00edculo de merchandising Taza de espresso apilable de 130 ml con fondo de arcilla Olympia. La taza de caf\u00e9 expreso Olympia tiene un dise\u00f1o apilable que ocupa poco espacio y una capacidad de 130\u00a0ml. Acabado mate. Se presenta en una caja de cart\u00f3n reciclado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\/","og_locale":"es_ES","og_type":"article","og_title":"Merchandising Taza de espresso apilable de 130 ml con fondo de arcilla Olympia para personalizar con logo - ADL","og_description":"Art\u00edculo de merchandising Taza de espresso apilable de 130 ml con fondo de arcilla Olympia. La taza de caf\u00e9 expreso Olympia tiene un dise\u00f1o apilable que ocupa poco espacio y una capacidad de 130\u00a0ml. Acabado mate. Se presenta en una caja de cart\u00f3n reciclado.","og_url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\/","og_site_name":"ADL Comunicaci\u00f3n","article_modified_time":"2026-09-02T08:24:16+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2024\/08\/10080501.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Merchandising Taza de espresso apilable de 130 ml con fondo de arcilla Olympia para personalizar con logo - ADL","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\/","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\/","name":"Merchandising Taza de espresso apilable de 130 ml con fondo de arcilla Olympia para personalizar con logo - ADL","isPartOf":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\/#primaryimage"},"image":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\/#primaryimage"},"thumbnailUrl":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2024\/08\/10080501.jpg","datePublished":"2026-09-02T04:45:32+00:00","dateModified":"2026-09-02T08:24:16+00:00","description":"Art\u00edculo de merchandising Taza de espresso apilable de 130 ml con fondo de arcilla Olympia. La taza de caf\u00e9 expreso Olympia tiene un dise\u00f1o apilable que ocupa poco espacio y una capacidad de 130\u00a0ml. Acabado mate. Se presenta en una caja de cart\u00f3n reciclado.","breadcrumb":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\/#primaryimage","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2024\/08\/10080501.jpg","contentUrl":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2024\/08\/10080501.jpg","width":1600,"height":1600,"caption":"Taza de espresso apilable de 130 ml con fondo de arcilla Olympia"},{"@type":"BreadcrumbList","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/taza-de-espresso-apilable-de-130-ml-con-fondo-de-arcilla-olympia-para-personalizar-con-logo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/adl-regalosempresa.com\/tiendaonline\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/adl-regalosempresa.com\/tiendaonline\/tienda\/"},{"@type":"ListItem","position":3,"name":"Taza de espresso apilable de 130 ml con fondo de arcilla Olympia para personalizar con logo"}]},{"@type":"WebSite","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/","name":"ADL Comunicaci\u00f3n","description":"Regalos de empresa","publisher":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adl-regalosempresa.com\/tiendaonline\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization","name":"ADL Comunicaci\u00f3n","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png","contentUrl":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png","width":407,"height":185,"caption":"ADL Comunicaci\u00f3n"},"image":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product\/135626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/media\/135628"}],"wp:attachment":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/media?parent=135626"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product_brand?post=135626"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product_cat?post=135626"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product_tag?post=135626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}