{"id":134383,"date":"2026-07-10T04:37:01","date_gmt":"2026-07-10T04:37:01","guid":{"rendered":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-para-personalizar-con-logo-3\/"},"modified":"2026-07-14T09:30:08","modified_gmt":"2026-07-14T09:30:08","slug":"polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo","status":"publish","type":"product","link":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo\/","title":{"rendered":"Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil para personalizar con logo"},"content":{"rendered":"<p>Tejido de poli\u00e9ster reciclado antibacteriano. Cuello de canal\u00e9 1&#215;1 y detalle en las mangas. Costuras cubiertas reforzadas en el cuello. Tapeta con 2 botones de cierre oculto. Detalles y hombros en contraste. Aberturas laterales en el dobladillo. Etiqueta extra\u00edble.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Descuentos por cantidades<\/strong><br \/>&#8211; a partir de 100 unidades: 7,72 \u20ac\/ud<br \/>&#8211; a partir de 250 unidades: 7,72 \u20ac\/ud<br \/>&#8211; a partir de 1000 unidades: 7,65 \u20ac\/ud<\/p>\n<p>Para cantidades superiores a las aqu\u00ed indicadas, no dudes en ponerte en contacto con nuestro departamento comercial o <a href='https:\/\/adl-regalosempresa.com\/tiendaonline\/solicitud-presupuesto\/'>pedirnos presupuesto personalizado<\/a>, ajustaremos el presupuesto a tus necesidades.<\/p>\n","protected":false},"featured_media":134387,"template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[5414,3649],"product_tag":[],"class_list":{"0":"post-134383","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-polos","7":"product_cat-ropa","8":"pa_color-azul-marino-blanco","9":"pa_color-azul-real-blanco","10":"pa_color-blanco-negro-intenso","11":"pa_color-negro-intenso-blanco","12":"pa_color-rojo-blanco","13":"pa_color-simple-azul","14":"pa_color-simple-blanco","15":"pa_color-simple-negro-intenso","16":"pa_color-simple-rojo","17":"pa_genero-hombre","18":"pa_marca-roly","19":"pa_material-punto-pique-con-un-acabado-cool-fit-50-poliester-reciclado-50-poliester-140-g-m2","20":"pa_peso-146-gr","21":"pa_talla-2xl","22":"pa_talla-s","23":"pa_talla-m","24":"pa_talla-l","25":"pa_talla-xl","26":"pa_talla-3xl","28":"first","29":"instock","30":"taxable","31":"shipping-taxable","32":"purchasable","33":"product-type-variable","34":"entry","35":"content-bg","36":"loop-entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Merchandising Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil para personalizar con logo - ADL<\/title>\n<meta name=\"description\" content=\"Art\u00edculo de merchandising Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil. Tejido de poli\u00e9ster reciclado antibacteriano. Cuello de canal\u00e9 1x1 y detalle en las mangas. Costuras cubiertas reforzadas en el cuello. Tapeta con 2 botones de cierre oculto. Detalles y hombros en contraste. Aberturas laterales en el dobladillo. Etiqueta extra\u00edble.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m\u00b2-tamil-para-personalizar-con-logo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Merchandising Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil para personalizar con logo - ADL\" \/>\n<meta property=\"og:description\" content=\"Art\u00edculo de merchandising Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil. Tejido de poli\u00e9ster reciclado antibacteriano. Cuello de canal\u00e9 1x1 y detalle en las mangas. Costuras cubiertas reforzadas en el cuello. Tapeta con 2 botones de cierre oculto. Detalles y hombros en contraste. Aberturas laterales en el dobladillo. Etiqueta extra\u00edble.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m\u00b2-tamil-para-personalizar-con-logo\/\" \/>\n<meta property=\"og:site_name\" content=\"ADL Comunicaci\u00f3n\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T09:30:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2024\/06\/R04028C.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Merchandising Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil para personalizar con logo - ADL\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo\/\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo\/\",\"name\":\"Merchandising Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil para personalizar con logo - ADL\",\"isPartOf\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2024\/06\/R04028C.jpg\",\"datePublished\":\"2026-07-10T04:37:01+00:00\",\"dateModified\":\"2026-07-14T09:30:08+00:00\",\"description\":\"Art\u00edculo de merchandising Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil. Tejido de poli\u00e9ster reciclado antibacteriano. Cuello de canal\u00e9 1x1 y detalle en las mangas. Costuras cubiertas reforzadas en el cuello. Tapeta con 2 botones de cierre oculto. Detalles y hombros en contraste. Aberturas laterales en el dobladillo. Etiqueta extra\u00edble.\",\"breadcrumb\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo\/#primaryimage\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2024\/06\/R04028C.jpg\",\"contentUrl\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2024\/06\/R04028C.jpg\",\"width\":1600,\"height\":1600,\"caption\":\"Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil para personalizar con logo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/\",\"name\":\"ADL Comunicaci\u00f3n\",\"description\":\"Regalos de empresa\",\"publisher\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization\",\"name\":\"ADL Comunicaci\u00f3n\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png\",\"contentUrl\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png\",\"width\":407,\"height\":185,\"caption\":\"ADL Comunicaci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Merchandising Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil para personalizar con logo - ADL","description":"Art\u00edculo de merchandising Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil. Tejido de poli\u00e9ster reciclado antibacteriano. Cuello de canal\u00e9 1x1 y detalle en las mangas. Costuras cubiertas reforzadas en el cuello. Tapeta con 2 botones de cierre oculto. Detalles y hombros en contraste. Aberturas laterales en el dobladillo. Etiqueta extra\u00edble.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m\u00b2-tamil-para-personalizar-con-logo\/","og_locale":"es_ES","og_type":"article","og_title":"Merchandising Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil para personalizar con logo - ADL","og_description":"Art\u00edculo de merchandising Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil. Tejido de poli\u00e9ster reciclado antibacteriano. Cuello de canal\u00e9 1x1 y detalle en las mangas. Costuras cubiertas reforzadas en el cuello. Tapeta con 2 botones de cierre oculto. Detalles y hombros en contraste. Aberturas laterales en el dobladillo. Etiqueta extra\u00edble.","og_url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m\u00b2-tamil-para-personalizar-con-logo\/","og_site_name":"ADL Comunicaci\u00f3n","article_modified_time":"2026-07-14T09:30:08+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2024\/06\/R04028C.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Merchandising Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil para personalizar con logo - ADL","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo\/","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo\/","name":"Merchandising Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil para personalizar con logo - ADL","isPartOf":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo\/#primaryimage"},"image":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo\/#primaryimage"},"thumbnailUrl":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2024\/06\/R04028C.jpg","datePublished":"2026-07-10T04:37:01+00:00","dateModified":"2026-07-14T09:30:08+00:00","description":"Art\u00edculo de merchandising Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil. Tejido de poli\u00e9ster reciclado antibacteriano. Cuello de canal\u00e9 1x1 y detalle en las mangas. Costuras cubiertas reforzadas en el cuello. Tapeta con 2 botones de cierre oculto. Detalles y hombros en contraste. Aberturas laterales en el dobladillo. Etiqueta extra\u00edble.","breadcrumb":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo\/#primaryimage","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2024\/06\/R04028C.jpg","contentUrl":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2024\/06\/R04028C.jpg","width":1600,"height":1600,"caption":"Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil"},{"@type":"BreadcrumbList","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/polo-deportivo-de-manga-corta-para-hombre-de-150-g-m%c2%b2-tamil-para-personalizar-con-logo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/adl-regalosempresa.com\/tiendaonline\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/adl-regalosempresa.com\/tiendaonline\/tienda\/"},{"@type":"ListItem","position":3,"name":"Polo deportivo de manga corta para hombre de 150 g\/m\u00b2 Tamil para personalizar con logo"}]},{"@type":"WebSite","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/","name":"ADL Comunicaci\u00f3n","description":"Regalos de empresa","publisher":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adl-regalosempresa.com\/tiendaonline\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization","name":"ADL Comunicaci\u00f3n","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png","contentUrl":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png","width":407,"height":185,"caption":"ADL Comunicaci\u00f3n"},"image":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product\/134383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/media\/134387"}],"wp:attachment":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/media?parent=134383"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product_brand?post=134383"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product_cat?post=134383"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product_tag?post=134383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}