{"id":120193,"date":"2026-05-20T04:33:03","date_gmt":"2026-05-20T04:33:03","guid":{"rendered":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-para-personalizar-con-logo\/"},"modified":"2026-05-24T07:37:47","modified_gmt":"2026-05-24T07:37:47","slug":"bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo","status":"publish","type":"product","link":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/","title":{"rendered":"Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe para personalizar con logo"},"content":{"rendered":"<p>Bid\u00f3n deportivo de una sola capa con dise\u00f1o recto y fabricado con Prevented Ocean Plastic. Los pl\u00e1sticos se recogen a menos de 50 km de una costa oce\u00e1nica o de una v\u00eda fluvial importante que desemboque en el oc\u00e9ano. Despu\u00e9s, se clasifica y transforma en pl\u00e1stico reciclado de alta calidad apto para alimentos. Cuenta con una tapa de rosca segura y est\u00e1 disponible en varios colores. Capacidad de 850 ml. Fabricado en el Reino Unido. Embalado en una bolsa compostable para el hogar. Mezcla y combina colores para crear el bid\u00f3n perfecto. Debido a la naturaleza del material reciclado, puede haber algunas peque\u00f1as marcas en el cuerpo de la botella.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Descuentos por cantidades<\/strong><br \/>&#8211; a partir de 100 unidades: 4,28 \u20ac\/ud<br \/>&#8211; a partir de 250 unidades: 4,11 \u20ac\/ud<br \/>&#8211; a partir de 500 unidades: 4,03 \u20ac\/ud<\/p>\n<p>Para cantidades superiores a las aqu\u00ed indicadas, no dudes en ponerte en contacto con nuestro departamento comercial o <a href='https:\/\/adl-regalosempresa.com\/tiendaonline\/solicitud-presupuesto\/'>pedirnos presupuesto personalizado<\/a>, ajustaremos el presupuesto a tus necesidades.<\/p>\n","protected":false},"featured_media":121337,"template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[3372,3373],"product_tag":[],"class_list":{"0":"post-120193","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-articulos-para-bebidas","7":"product_cat-botellas-de-agua","8":"pa_alto-229-cm","9":"pa_color-azul-azul","10":"pa_color-azul-blanco","11":"pa_color-azul-negro-intenso","12":"pa_color-carbon-blanco","13":"pa_color-carbon-negro-intenso","14":"pa_color-rojo-blanco","15":"pa_color-rojo-negro-intenso","16":"pa_color-rojo-rojo","17":"pa_color-simple-azul","18":"pa_color-simple-blanco","19":"pa_color-simple-gris","20":"pa_color-simple-negro-intenso","21":"pa_color-simple-rojo","22":"pa_diametro-735-cm","23":"pa_marca-unbranded","24":"pa_material-plastico-pcr-plastico-pp","25":"pa_peso-84-gr","27":"first","28":"instock","29":"taxable","30":"shipping-taxable","31":"purchasable","32":"product-type-variable","33":"entry","34":"content-bg","35":"loop-entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Merchandising Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe para personalizar con logo - ADL<\/title>\n<meta name=\"description\" content=\"Art\u00edculo de merchandising Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe. Bid\u00f3n deportivo de una sola capa con dise\u00f1o recto y fabricado con Prevented Ocean Plastic. Los pl\u00e1sticos se recogen a menos de 50 km de una costa oce\u00e1nica o de una v\u00eda fluvial importante que desemboque en el oc\u00e9ano. Despu\u00e9s, se clasifica y transforma en pl\u00e1stico reciclado de alta calidad apto para alimentos. Cuenta con una tapa de rosca segura y est\u00e1 disponible en varios colores. Capacidad de 850 ml. Fabricado en el Reino Unido. Embalado en una bolsa compostable para el hogar. Mezcla y combina colores para crear el bid\u00f3n perfecto. Debido a la naturaleza del material reciclado, puede haber algunas peque\u00f1as marcas en el cuerpo de la botella.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Merchandising Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe para personalizar con logo - ADL\" \/>\n<meta property=\"og:description\" content=\"Art\u00edculo de merchandising Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe. Bid\u00f3n deportivo de una sola capa con dise\u00f1o recto y fabricado con Prevented Ocean Plastic. Los pl\u00e1sticos se recogen a menos de 50 km de una costa oce\u00e1nica o de una v\u00eda fluvial importante que desemboque en el oc\u00e9ano. Despu\u00e9s, se clasifica y transforma en pl\u00e1stico reciclado de alta calidad apto para alimentos. Cuenta con una tapa de rosca segura y est\u00e1 disponible en varios colores. Capacidad de 850 ml. Fabricado en el Reino Unido. Embalado en una bolsa compostable para el hogar. Mezcla y combina colores para crear el bid\u00f3n perfecto. Debido a la naturaleza del material reciclado, puede haber algunas peque\u00f1as marcas en el cuerpo de la botella.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/\" \/>\n<meta property=\"og:site_name\" content=\"ADL Comunicaci\u00f3n\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-24T07:37:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2023\/01\/21048500.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Merchandising Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe para personalizar con logo - ADL\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/\",\"name\":\"Merchandising Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe para personalizar con logo - ADL\",\"isPartOf\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2023\/01\/21048500.jpg\",\"datePublished\":\"2026-05-20T04:33:03+00:00\",\"dateModified\":\"2026-05-24T07:37:47+00:00\",\"description\":\"Art\u00edculo de merchandising Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe. Bid\u00f3n deportivo de una sola capa con dise\u00f1o recto y fabricado con Prevented Ocean Plastic. Los pl\u00e1sticos se recogen a menos de 50 km de una costa oce\u00e1nica o de una v\u00eda fluvial importante que desemboque en el oc\u00e9ano. Despu\u00e9s, se clasifica y transforma en pl\u00e1stico reciclado de alta calidad apto para alimentos. Cuenta con una tapa de rosca segura y est\u00e1 disponible en varios colores. Capacidad de 850 ml. Fabricado en el Reino Unido. Embalado en una bolsa compostable para el hogar. Mezcla y combina colores para crear el bid\u00f3n perfecto. Debido a la naturaleza del material reciclado, puede haber algunas peque\u00f1as marcas en el cuerpo de la botella.\",\"breadcrumb\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/#primaryimage\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2023\/01\/21048500.jpg\",\"contentUrl\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2023\/01\/21048500.jpg\",\"width\":1600,\"height\":1600,\"caption\":\"Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe para personalizar con logo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/\",\"name\":\"ADL Comunicaci\u00f3n\",\"description\":\"Regalos de empresa\",\"publisher\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization\",\"name\":\"ADL Comunicaci\u00f3n\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png\",\"contentUrl\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png\",\"width\":407,\"height\":185,\"caption\":\"ADL Comunicaci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Merchandising Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe para personalizar con logo - ADL","description":"Art\u00edculo de merchandising Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe. Bid\u00f3n deportivo de una sola capa con dise\u00f1o recto y fabricado con Prevented Ocean Plastic. Los pl\u00e1sticos se recogen a menos de 50 km de una costa oce\u00e1nica o de una v\u00eda fluvial importante que desemboque en el oc\u00e9ano. Despu\u00e9s, se clasifica y transforma en pl\u00e1stico reciclado de alta calidad apto para alimentos. Cuenta con una tapa de rosca segura y est\u00e1 disponible en varios colores. Capacidad de 850 ml. Fabricado en el Reino Unido. Embalado en una bolsa compostable para el hogar. Mezcla y combina colores para crear el bid\u00f3n perfecto. Debido a la naturaleza del material reciclado, puede haber algunas peque\u00f1as marcas en el cuerpo de la botella.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/","og_locale":"es_ES","og_type":"article","og_title":"Merchandising Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe para personalizar con logo - ADL","og_description":"Art\u00edculo de merchandising Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe. Bid\u00f3n deportivo de una sola capa con dise\u00f1o recto y fabricado con Prevented Ocean Plastic. Los pl\u00e1sticos se recogen a menos de 50 km de una costa oce\u00e1nica o de una v\u00eda fluvial importante que desemboque en el oc\u00e9ano. Despu\u00e9s, se clasifica y transforma en pl\u00e1stico reciclado de alta calidad apto para alimentos. Cuenta con una tapa de rosca segura y est\u00e1 disponible en varios colores. Capacidad de 850 ml. Fabricado en el Reino Unido. Embalado en una bolsa compostable para el hogar. Mezcla y combina colores para crear el bid\u00f3n perfecto. Debido a la naturaleza del material reciclado, puede haber algunas peque\u00f1as marcas en el cuerpo de la botella.","og_url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/","og_site_name":"ADL Comunicaci\u00f3n","article_modified_time":"2026-05-24T07:37:47+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2023\/01\/21048500.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Merchandising Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe para personalizar con logo - ADL","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/","name":"Merchandising Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe para personalizar con logo - ADL","isPartOf":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/#primaryimage"},"image":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/#primaryimage"},"thumbnailUrl":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2023\/01\/21048500.jpg","datePublished":"2026-05-20T04:33:03+00:00","dateModified":"2026-05-24T07:37:47+00:00","description":"Art\u00edculo de merchandising Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe. Bid\u00f3n deportivo de una sola capa con dise\u00f1o recto y fabricado con Prevented Ocean Plastic. Los pl\u00e1sticos se recogen a menos de 50 km de una costa oce\u00e1nica o de una v\u00eda fluvial importante que desemboque en el oc\u00e9ano. Despu\u00e9s, se clasifica y transforma en pl\u00e1stico reciclado de alta calidad apto para alimentos. Cuenta con una tapa de rosca segura y est\u00e1 disponible en varios colores. Capacidad de 850 ml. Fabricado en el Reino Unido. Embalado en una bolsa compostable para el hogar. Mezcla y combina colores para crear el bid\u00f3n perfecto. Debido a la naturaleza del material reciclado, puede haber algunas peque\u00f1as marcas en el cuerpo de la botella.","breadcrumb":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/#primaryimage","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2023\/01\/21048500.jpg","contentUrl":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2023\/01\/21048500.jpg","width":1600,"height":1600,"caption":"Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe"},{"@type":"BreadcrumbList","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/articulos\/merchandising\/bidon-de-agua-con-tapa-de-rosca-de-850-ml-h2o-active-eco-vibe-para-personalizar-con-logo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/adl-regalosempresa.com\/tiendaonline\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/adl-regalosempresa.com\/tiendaonline\/tienda\/"},{"@type":"ListItem","position":3,"name":"Bid\u00f3n de agua con tapa de rosca de 850 ml H2O Active\u00ae Eco Vibe para personalizar con logo"}]},{"@type":"WebSite","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#website","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/","name":"ADL Comunicaci\u00f3n","description":"Regalos de empresa","publisher":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adl-regalosempresa.com\/tiendaonline\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#organization","name":"ADL Comunicaci\u00f3n","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/","url":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png","contentUrl":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-content\/uploads\/2017\/09\/logo-adl-wp.png","width":407,"height":185,"caption":"ADL Comunicaci\u00f3n"},"image":{"@id":"https:\/\/adl-regalosempresa.com\/tiendaonline\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product\/120193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/media\/121337"}],"wp:attachment":[{"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/media?parent=120193"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product_brand?post=120193"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product_cat?post=120193"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/adl-regalosempresa.com\/tiendaonline\/wp-json\/wp\/v2\/product_tag?post=120193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}